{"id":2005,"date":"2015-02-02T16:33:45","date_gmt":"2015-02-02T21:33:45","guid":{"rendered":"http:\/\/www.fmeat.org\/blog\/?p=2005"},"modified":"2017-08-14T15:17:55","modified_gmt":"2017-08-14T15:17:55","slug":"portraits-de-quartiers-dhiver-michel","status":"publish","type":"post","link":"https:\/\/www.fmeat.org\/blog\/portraits-de-quartiers-dhiver-michel\/","title":{"rendered":"PORTRAITS DE QUARTIERS D&rsquo;HIVER : Michel"},"content":{"rendered":"<p>Quand je lui ai demand\u00e9 de me \u00a0parler du FME il m&rsquo;a r\u00e9pondu que se serait moins long d&rsquo;\u00e9num\u00e9rer ce qu&rsquo;il ne ressent pas pour le festival, que le contraire! S&rsquo;il s&rsquo;implique \u00e0 fond comme il le fait c&rsquo;est qu&rsquo;il veut faire partie de ceux qui font bouger les choses, faire partie de quelque chose de grand.<\/p>\n<p><a href=\"http:\/\/www.fmeat.org\/blog\/wp-content\/uploads\/2015\/02\/DSC_6585.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-2006 aligncenter\" src=\"http:\/\/www.fmeat.org\/blog\/wp-content\/uploads\/2015\/02\/DSC_6585-300x199.jpg\" alt=\"DSC_6585\" width=\"300\" height=\"199\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand je lui ai demand\u00e9 de me \u00a0parler du FME il m&rsquo;a r\u00e9pondu que se serait moins long d&rsquo;\u00e9num\u00e9rer ce qu&rsquo;il ne ressent pas pour le festival, que le contraire! S&rsquo;il s&rsquo;implique \u00e0 fond comme il le fait c&rsquo;est qu&rsquo;il veut faire partie de ceux qui font bouger les choses, faire partie de quelque chose &hellip; <a href=\"https:\/\/www.fmeat.org\/blog\/portraits-de-quartiers-dhiver-michel\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">PORTRAITS DE QUARTIERS D&rsquo;HIVER : Michel<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,621],"tags":[],"class_list":["post-2005","post","type-post","status-publish","format-standard","hentry","category-non-classe","category-quartiers-dhiver-2015"],"_links":{"self":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/2005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/comments?post=2005"}],"version-history":[{"count":4,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/2005\/revisions"}],"predecessor-version":[{"id":2010,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/2005\/revisions\/2010"}],"wp:attachment":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/media?parent=2005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/categories?post=2005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/tags?post=2005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}