{"id":1367,"date":"2013-08-29T08:06:52","date_gmt":"2013-08-29T12:06:52","guid":{"rendered":"http:\/\/www.fmeat.org\/blog\/?p=1367"},"modified":"2017-08-14T15:21:53","modified_gmt":"2017-08-14T15:21:53","slug":"toronto-timmins-rouyn-miss-metal-fait-son-chemin-jusquau-fme","status":"publish","type":"post","link":"https:\/\/www.fmeat.org\/blog\/toronto-timmins-rouyn-miss-metal-fait-son-chemin-jusquau-fme\/","title":{"rendered":"Toronto-Timmins-Rouyn, Miss M\u00e9tal fait son chemin jusqu\u2019au FME!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Pis? T\u2019as pass\u00e9 un bel \u00e9t\u00e9? T\u2019as d\u00e9m\u00e9nag\u00e9 un po\u00eale dans des escaliers en colima\u00e7on un premier juillet? Tu t\u2019es fait dire que tu restais dans un \u00ab\u00a0\u00eelot de chaleur\u00a0\u00bb fait que \u00e7a t\u2019a donn\u00e9 une excuse pour aller visiter tes chums \u00e0 Laval? Ton maire est pris dans un scandale de fraude ou bien il fume du crack? Wow! T\u2019as vraiment besoin d\u2019une pause-sant\u00e9 \u00e0 Rouyn mon ami!<\/p>\n<p style=\"text-align: justify;\">Rouynorandiens et Rouynorandiennes, vous avez pass\u00e9 un \u00e9t\u00e9 au parc Aiguebelle, \u00e0 faire du canot, \u00e0 vous faire bronzer \u00e0 Crystal Beach pis \u00e0 danser au Cabaret? Essayez pas, on le sait!<\/p>\n<p style=\"text-align: justify;\">Peu importe ton \u00e9t\u00e9 mon ami, le temps du FME est arriv\u00e9 et il faut que tu te pr\u00e9pares! Tu es d\u00e9j\u00e0 au courant en ce qui a trait \u00e0 l\u2019essentiel\u00a0: poncho d\u2019urgence, bocks des ann\u00e9es pr\u00e9c\u00e9dentes, Gatorade. Mais sache que je ne te laisserai pas sans consignes de s\u00e9curit\u00e9 cette ann\u00e9e\u00a0: ton bien-\u00eatre et ta sant\u00e9 me tiennent \u00e0 c\u0153ur. Rappelle-toi que s\u2019il pleut, tu peux avoir beaucoup de plaisir dans ton imperm\u00e9able vert extralarge, mais fais tout de m\u00eame attention.<\/p>\n<p style=\"text-align: justify;\">Choses \u00e0 ne pas faire dans un poncho d\u2019urgence\u00a0:<\/p>\n<ol style=\"text-align: justify;\">\n<li>Faire un tournoi de poker (tu vas \u00eatre trop proche des autres pour bluffer \u00e0 ta guise).<\/li>\n<li>Fumer des cigarettes.<\/li>\n<li>Inviter 8 autres personnes \u00e0 dormir.<\/li>\n<li>Manger du homard (fais juste pas \u00e7a, man!).<\/li>\n<li>Jouer au jeu \u00abOp\u00e9ration\u00bb.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Par contre tu peux tr\u00e8s bien\u00a0:<\/p>\n<p style=\"text-align: justify;\">\n<ol style=\"text-align: justify;\">\n<li>Changer de paire de bobettes (admettons que t\u2019as pas dormi chez vous\u2026admettons).<\/li>\n<li>Cacher le t-shirt de Marie-Carmen que tu portes sans ironie aucune durant le festival.<\/li>\n<li>Trainer un bloc-notes pour essayer de demander des autographes aux musiciens qui vont \u00eatre dans la foule et revenir bredouille parce que\u00a0: t\u2019es m\u00eame pas<i> game<\/i>.<\/li>\n<li>\u00c9crire des po\u00e8mes d\u2019amour \u00e0 ta blonde en pleurant devant une performance incroyable (dans le genre Feist ou Half moon run l\u2019an pass\u00e9).<\/li>\n<li>\u00c9crire un po\u00e8me \u00e0 Harvey M\u00e9tal.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Dans le m\u00eame ordre d\u2019id\u00e9e, si tu me vois dans la rue et que tu me dis que t\u2019as une maudite bonne anecdote \u00e0 me raconter, ben peut-\u00eatre que t\u2019as pas rapport, mais je vais t\u2019\u00e9couter quand m\u00eame. Pis peut-\u00eatre m\u00eame m\u2019inspirer de ton histoire ou carr\u00e9ment la publier sur le blogue. C\u2019est qui le gars bizarre avec les cheveux magan\u00e9s pis des grosses lunettes qui disait que tout le monde allait avoir leur 15 minutes de gloire? Le chanteur de Cargo Culte? J\u2019me souviens pu.<\/p>\n<p style=\"text-align: justify;\">Mon plan? Cette ann\u00e9e encore, vraiment difficile de d\u00e9cider entre tous les bons bands\u2026<\/p>\n<p style=\"text-align: justify;\">Disons que je suis d\u00e9chir\u00e9e parce que les groupes que j\u2019ai d\u00e9j\u00e0 vus sont tellement bons que je pr\u00e9f\u00e9rerais ne pas les manquer et que ceux que je n\u2019ai jamais eu la chance de voir\u00a0m\u2019intriguent \u00e9norm\u00e9ment! Alors mon horaire n\u2019est qu\u2019une possibilit\u00e9 parmi tant d\u2019autres.<\/p>\n<p style=\"text-align: justify;\">H\u00f4tesses d\u2019Hilaire, Cargo Culte, Blonde Redhead, Indian Handcrafts, Foxtrott, Mononc Serge, Pyongyang, nuit \u00e9lectro, nuit m\u00e9tal\u2026.Et puis il para\u00eet que Les petites tounes, c\u2019est pour les enfants? Je serai prise \u00e0 Toronto quand ils joueront, mais si j\u2019\u00e9tais toi je me chercherais toute de suite un enfant \u00e0 emmener sous pr\u00e9texte que tu penses qu\u2019il aura ben du fonne (en r\u00e9alit\u00e9, c\u2019est toi qui va taper des mains mon grand).J\u2019ai vu Groenland \u00e0 Toronto et ils sont magiques. Je suis triste \u00e0 l\u2019id\u00e9e de manquer For\u00eat, le groupe qui s\u2019est tout d\u2019abord inspir\u00e9 de la po\u00e9sie de Kim Dor\u00e9, alors vas-y pour moi et tu me le raconteras! La programmation de cette ann\u00e9e nous force \u00e0 faire face \u00e0 des choix \u00e9prouvants, mais ce qui est positif c\u2019est que nous en sortons toujours gagnants gr\u00e2ce \u00e0 la qualit\u00e9 des groupes.<\/p>\n<p style=\"text-align: justify;\">Il se peut que je t\u2019accroche par le t-shirt FME 2009 que tu portes et que je te demande deux questions auxquelles je r\u00e9pondrai moi-m\u00eame ici, question de briser la glace entre toi et moi (ins\u00e9rer ici un \u00e9moticon bonhomme sourire qui fait un clin d\u2019\u0153il)\u00a0:<\/p>\n<p style=\"text-align: justify;\">1-Quel artiste as-tu le plus h\u00e2te de voir cette ann\u00e9e?<\/p>\n<p style=\"text-align: justify;\">2-Nomme-moi une chanson que tu as honte d\u2019aimer dans la vie. Tu le sais que tu ne devrais pas, mais quand elle joue tu tapes du pied et tu la fredonnes m\u00eame parfois quand tu es seul au chalet en train de travailler sur ton ponton.<\/p>\n<p style=\"text-align: justify;\">1-Nommer UN artiste, \u00e7a va pas??? Moi je r\u00e9pondrais Pyongyang, Vo\u00efvod, Dead Obies et Foxtrott. Cette question-l\u00e0 n\u2019est pas juste!<\/p>\n<p style=\"text-align: justify;\">2-Comme je suis un b\u00e9b\u00e9 de la fin des ann\u00e9es 70, j\u2019ai un amour du synth\u00e9tiseur gluant des ann\u00e9es 80. Le tout enrob\u00e9 d\u2019un mauvais solo de saxophone? Pourquoi pas? Un de mes plaisirs coupables, c\u2019est <i>Caribean queen<\/i> de Billy Ocean. En plus le vid\u00e9o est\u00a0 couleur p\u00eache (TOUTE est p\u00eache dans le video, TOUTE). Wow. Mais ces temps-ci, je fredonne du Marc Drouin et ses \u00e9chalottes en maudit\u2026<\/p>\n<p style=\"text-align: justify;\">Mon premier arr\u00eat ce soir\u00a0: Random recipe!<\/p>\n<p style=\"text-align: justify;\">\u00c0 venir\u00a0: ton horoscope! Manque pas \u00e7a sinon comment vas-tu faire pour poursuivre ta destin\u00e9e des quatre prochains jours? L\u2019astrologie ne ment jamais.<\/p>\n<p style=\"text-align: justify;\">\u00c9cris-nous et viens nous voir! \u00c0 bient\u00f4t!<\/p>\n<p style=\"text-align: justify;\">labouchecroche@gmail.com<\/p>\n<p style=\"text-align: justify;\">Harvey M\u00e9tal\u00a0: une fille qui a d\u00e9j\u00e0 vu Zamphir en show aux Promenades du Cuivre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pis? T\u2019as pass\u00e9 un bel \u00e9t\u00e9? T\u2019as d\u00e9m\u00e9nag\u00e9 un po\u00eale dans des escaliers en colima\u00e7on un premier juillet? Tu t\u2019es fait dire que tu restais dans un \u00ab\u00a0\u00eelot de chaleur\u00a0\u00bb fait que \u00e7a t\u2019a donn\u00e9 une excuse pour aller visiter tes chums \u00e0 Laval? Ton maire est pris dans un scandale de fraude ou &hellip; <a href=\"https:\/\/www.fmeat.org\/blog\/toronto-timmins-rouyn-miss-metal-fait-son-chemin-jusquau-fme\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Toronto-Timmins-Rouyn, Miss M\u00e9tal fait son chemin jusqu\u2019au FME!<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[314,613],"tags":[],"class_list":["post-1367","post","type-post","status-publish","format-standard","hentry","category-audrey","category-fme13"],"_links":{"self":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":7,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/1367\/revisions"}],"predecessor-version":[{"id":1385,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/posts\/1367\/revisions\/1385"}],"wp:attachment":[{"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/media?parent=1367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/categories?post=1367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fmeat.org\/blog\/wp-json\/wp\/v2\/tags?post=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}